{"id":2730,"date":"2024-11-13T10:26:46","date_gmt":"2024-11-13T13:26:46","guid":{"rendered":"https:\/\/siminova.com.br\/blog\/?p=2730"},"modified":"2025-12-08T09:50:32","modified_gmt":"2025-12-08T12:50:32","slug":"aprender-e-sensacional-lyric-video-programa-simrobotica","status":"publish","type":"post","link":"https:\/\/siminova.com.br\/blog\/2024\/11\/aprender-e-sensacional-lyric-video-programa-simrobotica\/","title":{"rendered":"Aprender \u00e9 Sensacional (Lyric Video)"},"content":{"rendered":"\n<center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/NiphkflgQ7Q?si=2A72QNTBSa1lwUf2&#038;autoplay=1\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\n\n\n<p><a href=\"https:\/\/www.youtube.com\/@siminova\"><\/a>TV SIM \u2014 A can\u00e7\u00e3o destaca a import\u00e2ncia da rob\u00f3tica e da inova\u00e7\u00e3o no aprendizado, incentivando a explora\u00e7\u00e3o e a cria\u00e7\u00e3o de um futuro melhor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TV SIM \u2014 A can\u00e7\u00e3o destaca a import\u00e2ncia da rob\u00f3tica e da inova\u00e7\u00e3o no aprendizado, incentivando a explora\u00e7\u00e3o e a cria\u00e7\u00e3o de um futuro melhor.<\/p>\n","protected":false},"author":10,"featured_media":2732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[51],"tags":[79],"class_list":["post-2730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tv-sim","tag-notts"],"_links":{"self":[{"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/posts\/2730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2730"}],"version-history":[{"count":6,"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/posts\/2730\/revisions"}],"predecessor-version":[{"id":2917,"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/posts\/2730\/revisions\/2917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/media\/2732"}],"wp:attachment":[{"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/siminova.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}